{"id":63,"date":"2017-09-04T11:40:51","date_gmt":"2017-09-04T14:40:51","guid":{"rendered":"https:\/\/www.wllsistemas.com.br\/blog\/?p=63"},"modified":"2017-09-12T11:50:48","modified_gmt":"2017-09-12T14:50:48","slug":"o-que-e-nfc-e-nota-fiscal-ao-consumidor-eletronica-entenda-como-funciona","status":"publish","type":"post","link":"https:\/\/www.wllsistemas.com.br\/blog\/o-que-e-nfc-e-nota-fiscal-ao-consumidor-eletronica-entenda-como-funciona","title":{"rendered":"O que \u00e9 NFC-e \u2013 Nota Fiscal ao Consumidor Eletr\u00f4nica? Entenda como funciona"},"content":{"rendered":"<p>O desenvolvimento da tecnologia computacional e dos sistemas de informa\u00e7\u00e3o proporciona a cria\u00e7\u00e3o de ferramentas que agilizam a gest\u00e3o de in\u00fameros procedimentos administrativos e fiscais. Uma dessas inova\u00e7\u00f5es foi a cria\u00e7\u00e3o de um programa para a emiss\u00e3o e controle de notas fiscais eletr\u00f4nicas, como a <a href=\"https:\/\/www.wllsistemas.com.br\/\">Nota Fiscal do Consumidor Eletr\u00f4nica (NFC-e)<\/a>.<\/p>\n<h4><strong>NFC-e reduz burocracia e gera economia para empresas<\/strong><\/h4>\n<p>A Nota Fiscal do Consumidor Eletr\u00f4nica foi criada para substituir o Emissor de Cupom Fiscal (ECF) e Nota Fiscal de Venda ao Consumidor (modelo 2). Este documento ainda n\u00e3o \u00e9 obrigat\u00f3rio, mas, gradativamente, os estados brasileiros est\u00e3o adotando o sistema. Ela j\u00e1 vigora nos estados de S\u00e3o Paulo, Rio de Janeiro, Rio Grande do Sul, Pernambuco e Amazonas. Embora a NFC-e n\u00e3o seja obrigat\u00f3ria, ela tem validade em todo o pa\u00eds.<\/p>\n<p>Para emitir a NFC-e, a empresa precisa instalar um programa emissor em seus computadores. Com a certifica\u00e7\u00e3o digital o documento \u00e9 transmitido \u00e0 Secretaria da Fazenda, via internet. Caso o sistema apresente algum problema, inviabilizando a transmiss\u00e3o da NFC-e, a empresa poder\u00e1 fazer o procedimento off-line, mas depois deve fazer a transmiss\u00e3o \u00e0 SEFAZ. Mesmo sendo um documento fiscal eletr\u00f4nico, a empresa precisa arquiv\u00e1-lo por cinco anos em seu pr\u00f3prio banco de dados ou contratando o servi\u00e7o de armazenamento.<\/p>\n<p>A NFC-e cont\u00e9m as mesmas informa\u00e7\u00f5es da nota fiscal tradicional como a identifica\u00e7\u00e3o de vendedor e comprador, produtos, pre\u00e7os das mercadorias e os tributos. Para emitir a NFC-e, a empresa n\u00e3o precisa comprar uma impressora especial nem requer autoriza\u00e7\u00e3o da Receita Federal. A empresa envia ao consumidor o DANFE NFC-e, que \u00e9 um documento fiscal simplificado. Com esse documento, o consumidor poder\u00e1 consultar a NFC-e no site da SEFAZ.<\/p>\n<p>Com esse sistema, a empresa reduz a burocracia e os gastos com a emiss\u00e3o de documentos fiscais em papel, fora o custo que teria para a aquisi\u00e7\u00e3o do Emissor de Cupom Fiscal, certificado pela Receita Federal.<\/p>\n<p>A NFC-e tamb\u00e9m pode ser emitida atrav\u00e9s do dispositivos m\u00f3veis como o smartphone e o tablet. Outra vantagem \u00e9 que o certificado digital da matriz, necess\u00e1rio para a emiss\u00e3o da NFC-e, pode ser utilizado pelas filiais. A certifica\u00e7\u00e3o digital \u00e9 importante tamb\u00e9m para o termo de garantia dos produtos.<\/p>\n<h4><strong>NFC-e agiliza atendimento ao consumidor<\/strong><\/h4>\n<p>A NFC-e beneficia o consumidor com a agilidade no atendimento, pois a emiss\u00e3o \u00e9 automatizada, seguindo diretamente para o e-mail cadastrado. Ao fazer as compras pela internet, o consumidor, al\u00e9m dos avisos eletr\u00f4nicos sobre o andamento do pedido, recebe a NFC-e pelo correio eletr\u00f4nico.<\/p>\n<p>Se for necess\u00e1rio efetuar uma devolu\u00e7\u00e3o ou troca da mercadoria, n\u00e3o \u00e9 necess\u00e1rio imprimir a NFC-e para enviar junto com o produto, pois tudo j\u00e1 est\u00e1 registrado na base de dados da empresa e da Secretaria da Fazenda do estado onde a empresa est\u00e1 sediada.<\/p>\n<p>Al\u00e9m da otimiza\u00e7\u00e3o de processos empresariais, a NFC-e tem outro aspecto positivo, a redu\u00e7\u00e3o do consumo de papel. Quanto menos papel a sociedade gastar, melhor para o meio ambiente e para a sustentabilidade das gera\u00e7\u00f5es futuras. O avan\u00e7o da tecnologia tamb\u00e9m estimula a amplia\u00e7\u00e3o do e-commerce e o surgimento de novos neg\u00f3cios para atender as necessidades da nova gera\u00e7\u00e3o de consumidores.<\/p>\n<h4><strong>Outros tipos de documentos ficais eletr\u00f4nicos<\/strong><\/h4>\n<p>Existem outros modelos de notas fiscais eletr\u00f4nicas. As notas fiscais modelo 1 e 1 A substitui a Nota Fiscal Eletr\u00f4nica (NF-e), emitida para vendas e presta\u00e7\u00e3o de servi\u00e7os. A Declara\u00e7\u00e3o de Servi\u00e7o pode ser trocada pela Nota Fiscal de Servi\u00e7os Eletr\u00f4nica (NFS-e). Documentos fiscais referentes ao transporte de cargas podem ser substitu\u00eddos pelo CT-e (Conhecimento de Transporte Eletr\u00f4nico.<\/p>\n<p>Estas informa\u00e7\u00f5es foram \u00fateis? Compartilhe e leia outros posts no blog!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O desenvolvimento da tecnologia computacional e dos sistemas de informa\u00e7\u00e3o proporciona a cria\u00e7\u00e3o de ferramentas que agilizam a gest\u00e3o de in\u00fameros procedimentos administrativos e fiscais. Uma dessas inova\u00e7\u00f5es foi a cria\u00e7\u00e3o de um programa para a emiss\u00e3o e controle de notas fiscais eletr\u00f4nicas, como a Nota Fiscal do Consumidor Eletr\u00f4nica (NFC-e). NFC-e reduz burocracia e <a class=\"more-link\" href=\"https:\/\/www.wllsistemas.com.br\/blog\/o-que-e-nfc-e-nota-fiscal-ao-consumidor-eletronica-entenda-como-funciona\">Leia mais&#8230; &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":64,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/63"}],"collection":[{"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":4,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/63\/revisions"}],"predecessor-version":[{"id":101,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/posts\/63\/revisions\/101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/media\/64"}],"wp:attachment":[{"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=63"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=63"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wllsistemas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}